{"id":2773,"date":"2023-10-16T07:48:49","date_gmt":"2023-10-16T07:48:49","guid":{"rendered":"https:\/\/tpaceurope.com\/careers\/senior-scrum-manager\/"},"modified":"2023-11-28T10:08:59","modified_gmt":"2023-11-28T10:08:59","slug":"gerente-de-scrum-senior","status":"publish","type":"page","link":"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/","title":{"rendered":"Gerente de Scrum Senior"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1937&#8243; bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb columns_placement=\u00bbbottom\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0a0a0a\u00bb overlay_strength=\u00bb0.8&#8243; gradient_direction=\u00bbleft_t_to_right_b\u00bb shape_divider_position=\u00bbbottom\u00bb shape_divider_height=\u00bb350&#8243; bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb parallax_bg_speed=\u00bbfast\u00bb shape_type=\u00bbmountains\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb9\/12&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][split_line_heading animation_type=\u00bbline-reveal-by-space\u00bb font_style=\u00bbh1&#8243; text_color=\u00bb#ffffff\u00bb line_reveal_by_space_text_effect=\u00bbdefault\u00bb content_alignment=\u00bbdefault\u00bb mobile_content_alignment=\u00bbinherit\u00bb link_target=\u00bb_self\u00bb text_content=\u00bbGerente de Scrum Senior \u00bb font_line_height=\u00bb1.3&#8243;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/12&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb5%\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb class=\u00bbxs-hidden\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb5\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbslight-fade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb delay=\u00bb300&#8243; offset=\u00bbvc_hidden-xs\u00bb][split_line_heading animation_type=\u00bbline-reveal-by-space\u00bb font_style=\u00bbp\u00bb text_color=\u00bb#ffffff\u00bb line_reveal_by_space_text_effect=\u00bbdefault\u00bb content_alignment=\u00bbdefault\u00bb mobile_content_alignment=\u00bbinherit\u00bb link_target=\u00bb_self\u00bb text_content=\u00bb\u00bfEst\u00e1s listo para aplicar tus conocimientos y experiencia a nuevos y emocionantes desaf\u00edos?\u00bb font_size=\u00bb18pt\u00bb][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbslight-fade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb delay=\u00bb300&#8243; offset=\u00bbvc_hidden-xs\u00bb][nectar_cta btn_style=\u00bbnext-section\u00bb btn_type=\u00bbdown-arrow-bordered\u00bb next_section_shadow=\u00bbnone\u00bb alignment=\u00bbright\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb5%\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb class=\u00bblg-hidden\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbslight-fade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb delay=\u00bb300&#8243; offset=\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm\u00bb][split_line_heading animation_type=\u00bbline-reveal-by-space\u00bb font_style=\u00bbp\u00bb text_color=\u00bb#ffffff\u00bb line_reveal_by_space_text_effect=\u00bbdefault\u00bb content_alignment=\u00bbdefault\u00bb mobile_content_alignment=\u00bbinherit\u00bb link_target=\u00bb_self\u00bb text_content=\u00bb\u00bfEst\u00e1s listo para aplicar tus conocimientos y experiencia a nuevos y emocionantes desaf\u00edos?\u00bb][\/split_line_heading][nectar_cta btn_style=\u00bbnext-section\u00bb btn_type=\u00bbdown-arrow-bordered\u00bb next_section_shadow=\u00bbnone\u00bb alignment=\u00bbleft\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb margin_bottom=\u00bb30&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb6%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb6%\u00bb constrain_group_2=\u00bbyes\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb class=\u00bbxs-hidden\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb offset=\u00bbvc_hidden-xs\u00bb][vc_custom_heading text=\u00bbDescripci\u00f3n\u00bb font_container=\u00bbtag:h2|font_size:20pt|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb offset=\u00bbvc_hidden-xs\u00bb][nectar_cta btn_style=\u00bbcurved-arrow-animation\u00bb heading_tag=\u00bbh6&#8243; button_color=\u00bbdefault\u00bb text_color=\u00bb#000000&#8243; text_color_hover=\u00bb#0762c8&#8243; button_border_color=\u00bb#cccccc\u00bb button_border_color_hover=\u00bb#0762c8&#8243; button_border_thickness=\u00bb1px\u00bb link_type=\u00bbregular\u00bb alignment=\u00bbright\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb constrain_group_3=\u00bbyes\u00bb constrain_group_4=\u00bbyes\u00bb display=\u00bbblock\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb link_text=\u00bbVolver a Carreras\u00bb padding_top=\u00bb15&#8243; padding_bottom=\u00bb15&#8243; padding_left=\u00bb40&#8243; padding_right=\u00bb40&#8243; url=\u00bb\/es\/carreras\/\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb class=\u00bblg-hidden\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb offset=\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm\u00bb][nectar_cta btn_style=\u00bbcurved-arrow-animation\u00bb heading_tag=\u00bbh6&#8243; button_color=\u00bbdefault\u00bb text_color=\u00bb#000000&#8243; text_color_hover=\u00bb#0762c8&#8243; button_border_color=\u00bb#cccccc\u00bb button_border_color_hover=\u00bb#0762c8&#8243; button_border_thickness=\u00bb1px\u00bb link_type=\u00bbregular\u00bb alignment=\u00bbleft\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb constrain_group_3=\u00bbyes\u00bb constrain_group_4=\u00bbyes\u00bb display=\u00bbblock\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb link_text=\u00bbVolver a Carreras\u00bb padding_top=\u00bb15&#8243; padding_bottom=\u00bb15&#8243; padding_left=\u00bb40&#8243; padding_right=\u00bb40&#8243; url=\u00bb\/es\/carreras\/\u00bb][vc_custom_heading text=\u00bbDescripci\u00f3n\u00bb font_container=\u00bbtag:h2|font_size:20pt|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb css=\u00bb.vc_custom_1700829707675{margin-top: 100px !important;}\u00bb][\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h6>General<\/h6>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]<strong>T\u00edtulo profesional:<\/strong> Gerente de Scrum Senior<\/p>\n<p><strong>Localizaci\u00f3n:<\/strong> Remoto en Europa<\/p>\n<p><strong>Tipo de contrato:<\/strong> Permanente o Freelance (tiempo completo)[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h6>N\u00famero de referencia<\/h6>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Category\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Job\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<p class=\"form-control-static\">001<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h6>Descripci\u00f3n general de la empresa<\/h6>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Category\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Job\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<p class=\"form-control-static\">Desafiante e innovadora es la mejor manera de describir a The Pineapple Corporation. Aqu\u00ed encontrar\u00e1s un reto profesional que te permitir\u00e1 aprender y crecer en todos los sentidos. Defendemos la innovaci\u00f3n y el pensamiento \u201cfuera de lo com\u00fan\u201d para desarrollar nuevas tecnolog\u00edas de Inteligencia Artificial. Nuestro objetivo es brindar el mejor servicio a nuestros clientes y tambi\u00e9n permitir que nuestros empleados logren sus prop\u00f3sitos profesionales.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h6>Introducci\u00f3n<\/h6>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Category\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Job\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<p class=\"form-control-static\">Buscamos un Senior Scrum Master con experiencia en proyectos tecnol\u00f3gicos. Como Scrum Master, colaborar\u00e1 estrechamente con nuestro cliente para comprender sus necesidades, desaf\u00edos y objetivos y facilitarles la tarea de cubrir las brechas de los sistemas y aumentar el valor de sus negocios y productos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h6>Descripci\u00f3n del puesto<\/h6>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Category\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<div id=\"ctl00_ctl00_ContentPlaceHolderWebContent_ContentPlaceHolderWebContent_trDescription_Job\" class=\"form-group\">\n<div class=\"col-sm-8\">\n<p>Este es un puesto de tiempo completo para un Scrum Master senior en ThePineappleCo, con flexibilidad para el trabajo remoto.<\/p>\n<p>Como Senior Scrum Master, ser\u00e1s responsable de liderar y facilitar la metodolog\u00eda \u00e1gil y asegurar que el equipo alcance sus objetivos y entregue valor de manera eficiente y efectiva. Trabajar\u00e1 en estrecha colaboraci\u00f3n con el equipo de desarrollo, el propietario del producto y el analista comercial para garantizar la implementaci\u00f3n exitosa de metodolog\u00edas \u00e1giles y la entrega del producto final. Adem\u00e1s, ser\u00e1s mentor del equipo y promover\u00e1s continuamente las mejores pr\u00e1cticas \u00e1giles. Debe tener buenas actitudes de trabajo en equipo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h6>Responsabilidades<\/h6>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb]<div class=\"nectar-fancy-ul\" data-list-icon=\"dot\" data-animation=\"false\" data-animation-delay=\"0\" data-spacing=\"15px\" data-alignment=\"left\"> \n<ul>\n<li>Liderar y facilitar reuniones diarias de Scrum, planificaci\u00f3n de sprints, revisiones y retrospectivas.<\/li>\n<li>Colaborar con el propietario del producto, el analista comercial y las partes interesadas para comprender los requisitos del proyecto y garantizar la creaci\u00f3n y priorizaci\u00f3n adecuadas del trabajo pendiente.<\/li>\n<li>Ayude al equipo a establecer compromisos de sprint realistas y a mantener un ritmo constante durante el desarrollo.<\/li>\n<li>Eliminar obst\u00e1culos y resolver problemas que puedan afectar el progreso del equipo.<\/li>\n<li>Promover una cultura de mejora continua, aprendizaje y autoorganizaci\u00f3n dentro del equipo.<\/li>\n<li>Asegurar las entregas de valor del Negocio en tiempo y forma y el producto final con la calidad esperada.<\/li>\n<li>Proporcionar orientaci\u00f3n y apoyo en la implementaci\u00f3n de pr\u00e1cticas \u00e1giles y t\u00e9cnicas de desarrollo.<\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbpadding-3-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h6>Requisitos de perfil<\/h6>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/4&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb]<div class=\"nectar-fancy-ul\" data-list-icon=\"dot\" data-animation=\"false\" data-animation-delay=\"0\" data-spacing=\"15px\" data-alignment=\"left\"> \n<ul>\n<li>Licenciatura o maestr\u00eda en inform\u00e1tica, ingenier\u00eda o carreras afines.<\/li>\n<li>Amplia trayectoria profesional en la gesti\u00f3n de proyectos tecnol\u00f3gicos.<\/li>\n<li>M\u00e1s de 8 a\u00f1os de experiencia como Scrum Master en proyectos de tecnolog\u00eda.<\/li>\n<li>Se requiere certificaci\u00f3n como Scrum Master (por ejemplo, CSM, PSM). La certificaci\u00f3n SAFe es una ventaja<\/li>\n<li>Amplio conocimiento de los principios y pr\u00e1cticas \u00e1giles, as\u00ed como su aplicaci\u00f3n en diferentes industrias.<\/li>\n<li>Fuerte conocimiento y experiencia con JIRA y otras herramientas de colaboraci\u00f3n \u00e1gil.<\/li>\n<li>Experiencia en coaching y tutor\u00eda de equipos Scrum, incluidas partes interesadas no t\u00e9cnicas.<\/li>\n<li>Actitud resolutiva y resolutiva.<\/li>\n<li>Excelentes habilidades de facilitaci\u00f3n en eventos Scrum como planificaci\u00f3n de sprints, revisi\u00f3n diaria de sprints y retrospectiva.<\/li>\n<li>Fuertes habilidades de comunicaci\u00f3n verbal y escrita con capacidad para comunicarse y presentar eficazmente a todos los niveles de la organizaci\u00f3n.<\/li>\n<li>Capacidad para liderar y motivar equipos, fomentando un ambiente de trabajo colaborativo.<\/li>\n<li>Capacidad para adaptarse a cambios r\u00e1pidos y gestionar m\u00faltiples proyectos simult\u00e1neamente.<\/li>\n<li>Se requiere nivel alto de ingl\u00e9s. El espa\u00f1ol es un plus.<\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][divider line_type=\u00bbFull Width Line\u00bb line_thickness=\u00bb1&#8243; divider_color=\u00bbdefault\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb class=\u00bbxs-hidden\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb offset=\u00bbvc_hidden-xs\u00bb][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb offset=\u00bbvc_hidden-xs\u00bb][nectar_cta btn_style=\u00bbcurved-arrow-animation\u00bb heading_tag=\u00bbh6&#8243; button_color=\u00bbdefault\u00bb text_color=\u00bb#000000&#8243; text_color_hover=\u00bb#0762c8&#8243; button_border_color=\u00bb#cccccc\u00bb button_border_color_hover=\u00bb#0762c8&#8243; button_border_thickness=\u00bb1px\u00bb link_type=\u00bbregular\u00bb alignment=\u00bbright\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb constrain_group_3=\u00bbyes\u00bb constrain_group_4=\u00bbyes\u00bb display=\u00bbblock\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb link_text=\u00bbVolver a Carreras\u00bb padding_top=\u00bb15&#8243; padding_bottom=\u00bb15&#8243; padding_left=\u00bb40&#8243; padding_right=\u00bb40&#8243; url=\u00bb\/es\/carreras\/\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb30&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb class=\u00bblg-hidden\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb offset=\u00bbvc_hidden-lg vc_hidden-md vc_hidden-sm\u00bb][nectar_cta btn_style=\u00bbcurved-arrow-animation\u00bb heading_tag=\u00bbh6&#8243; button_color=\u00bbdefault\u00bb text_color=\u00bb#000000&#8243; text_color_hover=\u00bb#0762c8&#8243; button_border_color=\u00bb#cccccc\u00bb button_border_color_hover=\u00bb#0762c8&#8243; button_border_thickness=\u00bb1px\u00bb link_type=\u00bbregular\u00bb alignment=\u00bbleft\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb constrain_group_3=\u00bbyes\u00bb constrain_group_4=\u00bbyes\u00bb display=\u00bbblock\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb link_text=\u00bbVolver a Carreras\u00bb padding_top=\u00bb15&#8243; padding_bottom=\u00bb15&#8243; padding_left=\u00bb40&#8243; padding_right=\u00bb40&#8243; url=\u00bb\/es\/carreras\/\u00bb margin_bottom=\u00bb60&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#f7f7f7&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding=\u00bb10&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][split_line_heading animation_type=\u00bbline-reveal-by-space\u00bb font_style=\u00bbh3&#8243; font_size_min=\u00bb20pt\u00bb font_size_max=\u00bb34pt\u00bb line_reveal_by_space_text_effect=\u00bbnone\u00bb content_alignment=\u00bbdefault\u00bb mobile_content_alignment=\u00bbinherit\u00bb link_target=\u00bb_self\u00bb text_content=\u00bbPor favor env\u00ede su solicitud y nos comunicaremos con usted\u00bb font_size_tablet=\u00bb18px\u00bb font_size_phone=\u00bb16px\u00bb][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2917-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"2917\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/2773#wpcf7-f2917-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2917\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2917-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div id=\"responsive-form\" class=\"clearfix\">\n\t<div class=\"form-row\">\n\t\t<div class=\"column-half\">\n\t\t\t<p>Nombre <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<p>Apellido <span class=\"wpcf7-form-control-wrap\" data-name=\"your-lastname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-lastname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-half\">\n\t\t\t<p>Email <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-half\">\n\t\t\t<p>Tel\u00e9fono <span class=\"wpcf7-form-control-wrap\" data-name=\"tel-784\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-784\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p>N\u00famero de referencia del puesto de trabajo* <span class=\"wpcf7-form-control-wrap\" data-name=\"menu-63\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-63\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"001\">001<\/option><option value=\"002\">002<\/option><option value=\"003\">003<\/option><option value=\"004\">004<\/option><option value=\"005\">005<\/option><option value=\"006\">006<\/option><option value=\"007\">007<\/option><option value=\"008\">008<\/option><option value=\"009\">009<\/option><option value=\"010\">010<\/option><option value=\"011\">011<\/option><option value=\"012\">012<\/option><option value=\"013\">013<\/option><option value=\"014\">014<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p>Mensaje <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"column-full\">\n\t\t\t<h4>Adjunta tu CV\n\t\t\t<\/h4>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"upload-file-192\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-drag-n-drop-file d-none\" aria-required=\"true\" aria-invalid=\"false\" type=\"file\" multiple=\"multiple\" data-name=\"upload-file-192\" data-type=\"pdf\" data-min=\"1\" data-max=\"2\" data-id=\"2917\" data-version=\"free version 1.3.9.8\" accept=\".pdf\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"form-row acceptance-row\">\n\t\t<p><label for=\"acceptance-39\" class=\"acceptance-label\"><br \/>\n<input type=\"checkbox\" id=\"acceptance-39\" name=\"acceptance-39\" \/> He le\u00eddo y acepto la <a href=\"\/es\/politica-de-privacidad\/\">pol\u00edtica de privacidad<\/a><br \/>\n<\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-row acceptance-row\">\n\t\t<p><label for=\"acceptance-40\" class=\"acceptance-label\"><br \/>\n<input type=\"checkbox\" id=\"acceptance-40\" name=\"acceptance-40\" \/> Acepto recibir informaci\u00f3n comercial sobre ofertas y promociones de THEPINEAPPLECO SL relacionadas con nuestro sector de CONSULTOR\u00cdA TECNOL\u00d3GICA. Consulta nuestra <a href=\"\/politica-de-privacidad\/\">pol\u00edtica de privacidad<\/a> para m\u00e1s informaci\u00f3n.<\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-row\">\n\t\t<div class=\"column-full\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Env\u00ede su solicitud\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<hr \/>\n\t<div style=\"font-size: 10pt; font-weight: 400;\">\n\t\t<p>En cumplimiento del art\u00edculo 13 Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (en adelante RGPD), as\u00ed como en el art\u00edculo 11 de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales (en adelante LOPD \u2013 GDD), le informamos que sobre:\n\t\t<\/p>\n\t\t<ul>\n\t\t\t<li>\n\t\t\t\t<p><b>Responsable del tratamiento:<\/b> THEPINEAPPLECO SL | B01679190 | C\/ DE LA DALIA, 66, ALCOBENDAS 28109 MADRID | <a href=\"mailto:adrian.kurucz@tpaceurope.com\">adrian.kurucz@tpaceurope.com<\/a>\n\t\t\t\t<\/p>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\t<p><b>Prop\u00f3sitos:<\/b> Respuesta a las consultas y solicitudes del interesado realizadas a trav\u00e9s de los canales dispuestos al efecto. Con la informaci\u00f3n previa y consentimiento expreso del interesado se podr\u00e1 enviar informaci\u00f3n comercial relacionada con nuestro sector de CONSULTOR\u00cdA TECNOL\u00d3GICA.\n\t\t\t\t<\/p>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\t<p><b>Legitimaci\u00f3n:<\/b> Atenci\u00f3n a las consultas y solicitudes del interesado, el tratamiento se basa en la ejecuci\u00f3n precontractual (art\u00edculo 6.1.b RGPD). Env\u00edo de informaci\u00f3n comercial con consentimiento expreso (art\u00edculos 6.1.a RGPD y art\u00edculo 22.2. LSSICE).\n\t\t\t\t<\/p>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\t<p><b>Retenci\u00f3n de datos:<\/b> Tus datos se conservar\u00e1n durante el tiempo estrictamente necesario y conforme a los plazos que puedes consultar en la pol\u00edtica de privacidad.\n\t\t\t\t<\/p>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\t<p><b>Destinatarios:<\/b> Siempre estar\u00e1 informado y, en su caso, se solicitar\u00e1 su consentimiento expreso para transferir sus datos personales o realizar transferencias internacionales de conformidad con la normativa vigente (arts. 13.1.e) y 44 RGPD, as\u00ed como el art. 11.1 y 40 LOPDGDD 3\/2018).\n\t\t\t\t<\/p>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\t<p><b>Derechos:<\/b> Puede ejercer sus derechos de acceso, rectificaci\u00f3n, supresi\u00f3n, portabilidad, limitaci\u00f3n de tratamiento y oposici\u00f3n escribiendo un correo electr\u00f3nico a <a href=\"mailto:adrian.kurucz@tpaceurope.com\">adrian.kurucz@tpaceurope.com<\/a> o en nuestra direcci\u00f3n indicada en los datos del responsable.\n\t\t\t\t<\/p>\n\t\t\t<\/li>\n\t\t\t<li>\n\t\t\t\t<p><b>Informaci\u00f3n adicional:<\/b>Puede consultar informaci\u00f3n adicional y detallada sobre Protecci\u00f3n de Datos escribiendo a <a href=\"mailto:adrian.kurucz@tpaceurope.com\">adrian.kurucz@tpaceurope.com<\/a> \/ <a href=\"https:\/\/tpaceurope.com\/\">WWW.THE-PINEAPPLE-CO.ES<\/a> o solicitando m\u00e1s informaci\u00f3n en nuestra oficina ubicada en la direcci\u00f3n indicada en el apartado \u201cResponsable\u201d.\n\t\t\t\t<\/p>\n\t\t\t<\/li>\n\t\t<\/ul>\n\t<\/div>\n<\/div><!--end responsive-form--><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"151\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1937&#8243; bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb columns_placement=\u00bbbottom\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0a0a0a\u00bb overlay_strength=\u00bb0.8&#8243; gradient_direction=\u00bbleft_t_to_right_b\u00bb shape_divider_position=\u00bbbottom\u00bb shape_divider_height=\u00bb350&#8243; bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2767,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2773","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gerente de Scrum Senior - The Pineapple Corporation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gerente de Scrum Senior - The Pineapple Corporation\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1937&#8243; bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb columns_placement=\u00bbbottom\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0a0a0a\u00bb overlay_strength=\u00bb0.8&#8243; gradient_direction=\u00bbleft_t_to_right_b\u00bb shape_divider_position=\u00bbbottom\u00bb shape_divider_height=\u00bb350&#8243; bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/\" \/>\n<meta property=\"og:site_name\" content=\"The Pineapple Corporation\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T10:08:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/carreras\\\/gerente-de-scrum-senior\\\/\",\"url\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/carreras\\\/gerente-de-scrum-senior\\\/\",\"name\":\"Gerente de Scrum Senior - The Pineapple Corporation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/#website\"},\"datePublished\":\"2023-10-16T07:48:49+00:00\",\"dateModified\":\"2023-11-28T10:08:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/carreras\\\/gerente-de-scrum-senior\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tpaceurope.com\\\/es\\\/carreras\\\/gerente-de-scrum-senior\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/carreras\\\/gerente-de-scrum-senior\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carreras\",\"item\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/carreras\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gerente de Scrum Senior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/\",\"name\":\"The Pineapple Corporation\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tpaceurope.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gerente de Scrum Senior - The Pineapple Corporation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/","og_locale":"es_ES","og_type":"article","og_title":"Gerente de Scrum Senior - The Pineapple Corporation","og_description":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_image=\u00bb1937&#8243; bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb full_height=\u00bbyes\u00bb columns_placement=\u00bbbottom\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0a0a0a\u00bb overlay_strength=\u00bb0.8&#8243; gradient_direction=\u00bbleft_t_to_right_b\u00bb shape_divider_position=\u00bbbottom\u00bb shape_divider_height=\u00bb350&#8243; bg_image_animation=\u00bbnone\u00bb parallax_bg=\u00bbtrue\u00bb...","og_url":"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/","og_site_name":"The Pineapple Corporation","article_modified_time":"2023-11-28T10:08:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/","url":"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/","name":"Gerente de Scrum Senior - The Pineapple Corporation","isPartOf":{"@id":"https:\/\/tpaceurope.com\/es\/#website"},"datePublished":"2023-10-16T07:48:49+00:00","dateModified":"2023-11-28T10:08:59+00:00","breadcrumb":{"@id":"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tpaceurope.com\/es\/carreras\/gerente-de-scrum-senior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tpaceurope.com\/es\/"},{"@type":"ListItem","position":2,"name":"Carreras","item":"https:\/\/tpaceurope.com\/es\/carreras\/"},{"@type":"ListItem","position":3,"name":"Gerente de Scrum Senior"}]},{"@type":"WebSite","@id":"https:\/\/tpaceurope.com\/es\/#website","url":"https:\/\/tpaceurope.com\/es\/","name":"The Pineapple Corporation","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tpaceurope.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/pages\/2773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/comments?post=2773"}],"version-history":[{"count":10,"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/pages\/2773\/revisions"}],"predecessor-version":[{"id":3122,"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/pages\/2773\/revisions\/3122"}],"up":[{"embeddable":true,"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/pages\/2767"}],"wp:attachment":[{"href":"https:\/\/tpaceurope.com\/es\/wp-json\/wp\/v2\/media?parent=2773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}